{"id":23459,"date":"2019-05-06T09:36:01","date_gmt":"2019-11-13T12:21:26","guid":{"rendered":"https:\/\/newgarden.es\/shop\/sin%20categor\u00eda\/kaktus-lime-100\/"},"modified":"2021-07-28T12:35:55","modified_gmt":"2021-07-28T10:35:55","slug":"kaktus-lime-100","status":"publish","type":"product","link":"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/","title":{"rendered":"KAKTUS LIME 100"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column el_class=&#8221;descripcion_producto&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: justify\"><em>* KAKTUS \u00e8 una lampada da terra ispirata a un cactus messicano. Kaktus \u00e8 disponibile in verde lime o bianco. <\/em><\/p>\n<p style=\"text-align: justify\">Questo prodotto \u00e8 dotato del nuovo sistema di illuminazione con cavo LED TUBE brevettato da Newgarden.<\/p>\n<p style=\"text-align: justify\"><em>Tutti i prodotti Newgarden sono realizzati in polietilene, quindi sono leggeri e molto resistenti alle temperature estreme. Sono inoltre protetti dai raggi UV, rendendo la vita del prodotto straordinariamente lunga. <\/em><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221;][vc_column][vc_single_image image=&#8221;6566&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_btn title=&#8221;SCHEDA TECNICA&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#009bc2&#8243; custom_text=&#8221;#ffffff&#8221; shape=&#8221;square&#8221; link=&#8221;url:https%3A%2F%2Fwww.newgarden.es%2Fwp-content%2Fuploads%2F2018%2F02%2FKAAKTUS-100-1.pdf|target:%20_blank|&#8221; el_class=&#8221;btn_descargar_ficha&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_btn title=&#8221;MANUALE DI ISTRUZIONI&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#009bc2&#8243; custom_text=&#8221;#ffffff&#8221; shape=&#8221;square&#8221; link=&#8221;url:https%3A%2F%2Fnewgarden.es%2Finstrucciones%2F||target:%20_blank|&#8221; el_class=&#8221;btn_descargar_ficha&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<h1 style=\"font-size: 12px\">Lampada da terra decorativa a forma di cactus<\/h1>\n","protected":false},"featured_media":53975,"template":"","meta":[],"product_cat":[1697,974,985,1250],"product_tag":[955],"class_list":{"0":"post-23459","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-productos-it","7":"product_cat-lightdeco-it","8":"product_cat-lampade-da-terra","9":"product_cat-lampade-da-terra-interne","10":"product_tag-cavo","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>KAKTUS lampada da terra decorativa a forma di cactus<\/title>\n<meta name=\"description\" content=\"KAKTUS \u00e8 una lampada da terra ispirata da un cactus messicano. Kaktus \u00e8 disponibile in calce perfetta verde o bianco per qualsiasi angolo della vostra casa o in ufficio terrazza con giardino. Equipaggiato con il TUBO LED nuovo cavo sistema di illuminazione brevettato Newgarden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KAKTUS lampada da terra decorativa a forma di cactus\" \/>\n<meta property=\"og:description\" content=\"KAKTUS \u00e8 una lampada da terra ispirata da un cactus messicano. Kaktus \u00e8 disponibile in calce perfetta verde o bianco per qualsiasi angolo della vostra casa o in ufficio terrazza con giardino. Equipaggiato con il TUBO LED nuovo cavo sistema di illuminazione brevettato Newgarden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/\" \/>\n<meta property=\"og:site_name\" content=\"Newgarden\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-28T10:35:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newgarden.es\/wp-content\/uploads\/2019\/05\/KAKTUS_100_CABLE_1200X1200-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/\",\"url\":\"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/\",\"name\":\"KAKTUS lampada da terra decorativa a forma di cactus\",\"isPartOf\":{\"@id\":\"https:\/\/newgarden.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newgarden.es\/wp-content\/uploads\/2019\/05\/KAKTUS_100_CABLE_1200X1200-12.jpg\",\"datePublished\":\"2019-11-13T12:21:26+00:00\",\"dateModified\":\"2021-07-28T10:35:55+00:00\",\"description\":\"KAKTUS \u00e8 una lampada da terra ispirata da un cactus messicano. Kaktus \u00e8 disponibile in calce perfetta verde o bianco per qualsiasi angolo della vostra casa o in ufficio terrazza con giardino. Equipaggiato con il TUBO LED nuovo cavo sistema di illuminazione brevettato Newgarden.\",\"breadcrumb\":{\"@id\":\"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/#primaryimage\",\"url\":\"https:\/\/newgarden.es\/wp-content\/uploads\/2019\/05\/KAKTUS_100_CABLE_1200X1200-12.jpg\",\"contentUrl\":\"https:\/\/newgarden.es\/wp-content\/uploads\/2019\/05\/KAKTUS_100_CABLE_1200X1200-12.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newgarden.es\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collezione\",\"item\":\"https:\/\/newgarden.es\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KAKTUS LIME 100\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newgarden.es\/#website\",\"url\":\"https:\/\/newgarden.es\/\",\"name\":\"Newgarden\",\"description\":\"Be happy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newgarden.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KAKTUS lampada da terra decorativa a forma di cactus","description":"KAKTUS \u00e8 una lampada da terra ispirata da un cactus messicano. Kaktus \u00e8 disponibile in calce perfetta verde o bianco per qualsiasi angolo della vostra casa o in ufficio terrazza con giardino. Equipaggiato con il TUBO LED nuovo cavo sistema di illuminazione brevettato Newgarden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/","og_locale":"it_IT","og_type":"article","og_title":"KAKTUS lampada da terra decorativa a forma di cactus","og_description":"KAKTUS \u00e8 una lampada da terra ispirata da un cactus messicano. Kaktus \u00e8 disponibile in calce perfetta verde o bianco per qualsiasi angolo della vostra casa o in ufficio terrazza con giardino. Equipaggiato con il TUBO LED nuovo cavo sistema di illuminazione brevettato Newgarden.","og_url":"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/","og_site_name":"Newgarden","article_modified_time":"2021-07-28T10:35:55+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/newgarden.es\/wp-content\/uploads\/2019\/05\/KAKTUS_100_CABLE_1200X1200-12.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/","url":"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/","name":"KAKTUS lampada da terra decorativa a forma di cactus","isPartOf":{"@id":"https:\/\/newgarden.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/#primaryimage"},"image":{"@id":"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/#primaryimage"},"thumbnailUrl":"https:\/\/newgarden.es\/wp-content\/uploads\/2019\/05\/KAKTUS_100_CABLE_1200X1200-12.jpg","datePublished":"2019-11-13T12:21:26+00:00","dateModified":"2021-07-28T10:35:55+00:00","description":"KAKTUS \u00e8 una lampada da terra ispirata da un cactus messicano. Kaktus \u00e8 disponibile in calce perfetta verde o bianco per qualsiasi angolo della vostra casa o in ufficio terrazza con giardino. Equipaggiato con il TUBO LED nuovo cavo sistema di illuminazione brevettato Newgarden.","breadcrumb":{"@id":"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/#primaryimage","url":"https:\/\/newgarden.es\/wp-content\/uploads\/2019\/05\/KAKTUS_100_CABLE_1200X1200-12.jpg","contentUrl":"https:\/\/newgarden.es\/wp-content\/uploads\/2019\/05\/KAKTUS_100_CABLE_1200X1200-12.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/newgarden.es\/it\/shop\/lightdeco-it\/lampade-da-terra\/kaktus-lime-100\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newgarden.es\/it\/"},{"@type":"ListItem","position":2,"name":"Collezione","item":"https:\/\/newgarden.es\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"KAKTUS LIME 100"}]},{"@type":"WebSite","@id":"https:\/\/newgarden.es\/#website","url":"https:\/\/newgarden.es\/","name":"Newgarden","description":"Be happy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newgarden.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"df_price":126,"df_sale_price":"","df_regular_price":126,"df_image_link":"https:\/\/newgarden.es\/wp-content\/uploads\/2019\/05\/KAKTUS_100_CABLE_1200X1200-12.jpg","_links":{"self":[{"href":"https:\/\/newgarden.es\/it\/wp-json\/wp\/v2\/product\/23459"}],"collection":[{"href":"https:\/\/newgarden.es\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/newgarden.es\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newgarden.es\/it\/wp-json\/wp\/v2\/media\/53975"}],"wp:attachment":[{"href":"https:\/\/newgarden.es\/it\/wp-json\/wp\/v2\/media?parent=23459"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/newgarden.es\/it\/wp-json\/wp\/v2\/product_cat?post=23459"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/newgarden.es\/it\/wp-json\/wp\/v2\/product_tag?post=23459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}